{"id":26423,"date":"2026-05-12T15:15:23","date_gmt":"2026-05-12T18:15:23","guid":{"rendered":"https:\/\/bricspolicycenter.org\/?p=26423"},"modified":"2026-05-12T15:25:09","modified_gmt":"2026-05-12T18:25:09","slug":"brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china","status":"publish","type":"post","link":"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/","title":{"rendered":"BRICS Policy Center\/PUC-Rio Welcomes Fellow Yang Qian from China"},"content":{"rendered":"<p>In 2026, the BRICS Policy Center\/PUC-Rio welcomed fellow Yang Qian, who is working with the Cooperation and Development Financing (LACID) group, coordinated by professor and researcher Maria Elena Rodriguez.<\/p>\n<p>Yang Qian is a professor at Hebei University and a researcher at the university\u2019s Center for Latin American Studies, where she also earned her master\u2019s degree in World Economics. She holds a Ph.D. in World Economics from the Latin American Institute of the Chinese Academy of Social Sciences (CASS). Her main areas of research involve financial cooperation between China and Latin America and Latin American monetary and financial policies.<\/p>\n<p>In an interview, Yang shares more details about her academic career, including her time at BPC\/PUC-Rio and her views on topics related to her field of research.<\/p>\n<p>Click the button below to access the interview.<\/p>\n<a href=\"https:\/\/acrobat.adobe.com\/id\/urn:aaid:sc:US:991e3b05-9818-4e80-ae5f-94b34005deac\" target=\"_blank\"  class=\"qbutton \" style=\"\">Read here <\/a>\n","protected":false},"excerpt":{"rendered":"<p>In 2026, the BRICS Policy Center\/PUC-Rio welcomed fellow Yang Qian, who is working with the Cooperation and Development Financing (LACID) group, coordinated by professor and researcher Maria Elena Rodriguez. Yang&#8230;<\/p>\n","protected":false},"author":18,"featured_media":26422,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[840,218],"tags":[831,1577,3543,1403],"class_list":["post-26423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticia-destaque-en","category-news","tag-secao-06"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BRICS Policy Center\/PUC-Rio Welcomes Fellow Yang Qian from China - brq<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BRICS Policy Center\/PUC-Rio Welcomes Fellow Yang Qian from China - brq\" \/>\n<meta property=\"og:description\" content=\"In 2026, the BRICS Policy Center\/PUC-Rio welcomed fellow Yang Qian, who is working with the Cooperation and Development Financing (LACID) group, coordinated by professor and researcher Maria Elena Rodriguez. Yang...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/\" \/>\n<meta property=\"og:site_name\" content=\"brq\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T18:15:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T18:25:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bricspolicycenter.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.37.34-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Adm BPC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adm BPC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/\",\"url\":\"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/\",\"name\":\"BRICS Policy Center\/PUC-Rio Welcomes Fellow Yang Qian from China - brq\",\"isPartOf\":{\"@id\":\"https:\/\/bricspolicycenter.org\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/bricspolicycenter.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.37.34-1.jpeg\",\"datePublished\":\"2026-05-12T18:15:23+00:00\",\"dateModified\":\"2026-05-12T18:25:09+00:00\",\"author\":{\"@id\":\"https:\/\/bricspolicycenter.org\/en\/#\/schema\/person\/f34bc4c22f015ebcb023cebab0e0c9e4\"},\"breadcrumb\":{\"@id\":\"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/#primaryimage\",\"url\":\"https:\/\/bricspolicycenter.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.37.34-1.jpeg\",\"contentUrl\":\"https:\/\/bricspolicycenter.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.37.34-1.jpeg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/bricspolicycenter.org\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BRICS Policy Center\/PUC-Rio Welcomes Fellow Yang Qian from China\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bricspolicycenter.org\/en\/#website\",\"url\":\"https:\/\/bricspolicycenter.org\/en\/\",\"name\":\"brq\",\"description\":\"S\u00f3 mais um site WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bricspolicycenter.org\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/bricspolicycenter.org\/en\/#\/schema\/person\/f34bc4c22f015ebcb023cebab0e0c9e4\",\"name\":\"Adm BPC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/bricspolicycenter.org\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/52c5584f583eb4ce2f4ed6fc37be38eb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/52c5584f583eb4ce2f4ed6fc37be38eb?s=96&d=mm&r=g\",\"caption\":\"Adm BPC\"},\"url\":\"https:\/\/bricspolicycenter.org\/en\/author\/admbpc\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BRICS Policy Center\/PUC-Rio Welcomes Fellow Yang Qian from China - brq","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/","og_locale":"en_US","og_type":"article","og_title":"BRICS Policy Center\/PUC-Rio Welcomes Fellow Yang Qian from China - brq","og_description":"In 2026, the BRICS Policy Center\/PUC-Rio welcomed fellow Yang Qian, who is working with the Cooperation and Development Financing (LACID) group, coordinated by professor and researcher Maria Elena Rodriguez. Yang...","og_url":"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/","og_site_name":"brq","article_published_time":"2026-05-12T18:15:23+00:00","article_modified_time":"2026-05-12T18:25:09+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/bricspolicycenter.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.37.34-1.jpeg","type":"image\/jpeg"}],"author":"Adm BPC","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Adm BPC","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/","url":"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/","name":"BRICS Policy Center\/PUC-Rio Welcomes Fellow Yang Qian from China - brq","isPartOf":{"@id":"https:\/\/bricspolicycenter.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/#primaryimage"},"image":{"@id":"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/#primaryimage"},"thumbnailUrl":"https:\/\/bricspolicycenter.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.37.34-1.jpeg","datePublished":"2026-05-12T18:15:23+00:00","dateModified":"2026-05-12T18:25:09+00:00","author":{"@id":"https:\/\/bricspolicycenter.org\/en\/#\/schema\/person\/f34bc4c22f015ebcb023cebab0e0c9e4"},"breadcrumb":{"@id":"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/#primaryimage","url":"https:\/\/bricspolicycenter.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.37.34-1.jpeg","contentUrl":"https:\/\/bricspolicycenter.org\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-12-at-13.37.34-1.jpeg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/bricspolicycenter.org\/en\/brics-policy-center-puc-rio-welcomes-fellow-yang-qian-from-china\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/bricspolicycenter.org\/en\/"},{"@type":"ListItem","position":2,"name":"BRICS Policy Center\/PUC-Rio Welcomes Fellow Yang Qian from China"}]},{"@type":"WebSite","@id":"https:\/\/bricspolicycenter.org\/en\/#website","url":"https:\/\/bricspolicycenter.org\/en\/","name":"brq","description":"S\u00f3 mais um site WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bricspolicycenter.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/bricspolicycenter.org\/en\/#\/schema\/person\/f34bc4c22f015ebcb023cebab0e0c9e4","name":"Adm BPC","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bricspolicycenter.org\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/52c5584f583eb4ce2f4ed6fc37be38eb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/52c5584f583eb4ce2f4ed6fc37be38eb?s=96&d=mm&r=g","caption":"Adm BPC"},"url":"https:\/\/bricspolicycenter.org\/en\/author\/admbpc\/"}]}},"_links":{"self":[{"href":"https:\/\/bricspolicycenter.org\/en\/wp-json\/wp\/v2\/posts\/26423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bricspolicycenter.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bricspolicycenter.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bricspolicycenter.org\/en\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/bricspolicycenter.org\/en\/wp-json\/wp\/v2\/comments?post=26423"}],"version-history":[{"count":2,"href":"https:\/\/bricspolicycenter.org\/en\/wp-json\/wp\/v2\/posts\/26423\/revisions"}],"predecessor-version":[{"id":26428,"href":"https:\/\/bricspolicycenter.org\/en\/wp-json\/wp\/v2\/posts\/26423\/revisions\/26428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bricspolicycenter.org\/en\/wp-json\/wp\/v2\/media\/26422"}],"wp:attachment":[{"href":"https:\/\/bricspolicycenter.org\/en\/wp-json\/wp\/v2\/media?parent=26423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bricspolicycenter.org\/en\/wp-json\/wp\/v2\/categories?post=26423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bricspolicycenter.org\/en\/wp-json\/wp\/v2\/tags?post=26423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}